{"id":169,"date":"2023-03-06T02:08:23","date_gmt":"2023-03-06T02:08:23","guid":{"rendered":"https:\/\/amsnorthshore.org\/?page_id=169"},"modified":"2023-03-06T02:13:04","modified_gmt":"2023-03-06T02:13:04","slug":"volunteer","status":"publish","type":"page","link":"https:\/\/amsnorthshore.org\/index.php\/volunteer\/","title":{"rendered":"Volunteer"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"169\" class=\"elementor elementor-169\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-226a983 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"226a983\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-845b797\" data-id=\"845b797\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20ab1c4 elementor-widget elementor-widget-heading\" data-id=\"20ab1c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 11-03-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Please apply to join our volunteers! <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5f088b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5f088b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fad2556\" data-id=\"fad2556\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-780783e elementor-widget elementor-widget-wpforms\" data-id=\"780783e\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-173\"><form id=\"wpforms-form-173\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"173\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/169\" data-token=\"408ecb56d6c507d8ca3a651b57c79697\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-173-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-173-field_1\">First Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-173-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-173-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-173-field_2\">Last Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-173-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/div><div id=\"wpforms-173-field_3-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-173-field_3\">Phone Numbers <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" pattern=\"\\d*\" id=\"wpforms-173-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-173-field_4-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-173-field_4\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-173-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-173-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-173-field_5\">Profession \/ Experience \/ Desired Position <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-173-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-173-field_6-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-173-field_6\">Please tell us about you. What can you do for us? What hours are you available? <\/label><textarea id=\"wpforms-173-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"173\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-173\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"https:\/\/amsnorthshore.org\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Please apply to join our volunteers!<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/amsnorthshore.org\/index.php\/wp-json\/wp\/v2\/pages\/169"}],"collection":[{"href":"https:\/\/amsnorthshore.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amsnorthshore.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amsnorthshore.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amsnorthshore.org\/index.php\/wp-json\/wp\/v2\/comments?post=169"}],"version-history":[{"count":7,"href":"https:\/\/amsnorthshore.org\/index.php\/wp-json\/wp\/v2\/pages\/169\/revisions"}],"predecessor-version":[{"id":185,"href":"https:\/\/amsnorthshore.org\/index.php\/wp-json\/wp\/v2\/pages\/169\/revisions\/185"}],"wp:attachment":[{"href":"https:\/\/amsnorthshore.org\/index.php\/wp-json\/wp\/v2\/media?parent=169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}